{"id":8006,"date":"2020-07-22T11:12:00","date_gmt":"2020-07-22T09:12:00","guid":{"rendered":"https:\/\/abm-tecna.com\/toiles-et-tamis-pour-cribles\/"},"modified":"2021-05-03T14:21:19","modified_gmt":"2021-05-03T12:21:19","slug":"zeefnetten-en-zeefschermen-voor-trilzeven","status":"publish","type":"page","link":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/","title":{"rendered":"Zeefnetten en Zeefschermen voor Trilzeven"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;Aan- en afvoersystemen voor conveyors&#8221; font_container=&#8221;tag:div|font_size:16|text_align:left|color:%23020202&#8243; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;breadcrumb&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:div|font_size:16|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221; link=&#8221;|||&#8221; el_class=&#8221;breadcrumb&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_custom_heading text=&#8221;Page pr\u00e9c\u00e9dente&#8221; font_container=&#8221;tag:div|font_size:16|text_align:right|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;none&#8221; link=&#8221;url:http%3A%2F%2Fabm-tecna.be%2Ffr%2Fconvoyeurs-a-bande%2F|title:Bandes%20transporteuses%20caoutchouc||&#8221; el_id=&#8221;goBack&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_highlighted_text color_type=&#8221;gradient&#8221; highlight_color=&#8221;#f8971d&#8221; secondary_color=&#8221;rgba(0,0,0,0.01)&#8221; style=&#8221;regular_underline&#8221; underline_thickness=&#8221;default&#8221; delay=&#8221;250&#8243;]\n<h2><em>Ons gamma<br \/>\n<\/em><\/h2>\n[\/nectar_highlighted_text][vc_column_text]\n<h3>Voor het onderhoud van uw trilzeven<\/h3>\n<ul>\n<li>Een uitstekende prijs\/kwaliteit verhouding<\/li>\n<li>Korte leveringstermijnen<\/li>\n<li>Speciale uitvoeringen op aanvraag<\/li>\n<\/ul>\n[\/vc_column_text][vc_column_text]\n<h3>Zeefnetten uit hoogwaardig koolstofstaal<\/h3>\n<ul>\n<li>Voor golvende of vlakke oppervlakken<\/li>\n<li>Types die het mogelijk maken om fijne, middelgrote en grove producten te selecteren met een korrelgroottenauwkeurigheid aangepast aan uw toepassing<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;5021&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][toggles style=&#8221;minimal_small&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Kenmerken&#8221;][image_with_animation image_url=&#8221;5026&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h3>Anti kleef zeefnetten (DIN 4185\/3)<\/h3>\n<ul>\n<li>Voor vlakke oppervlakken<\/li>\n<li>Aanbevolen voor klevende producten<\/li>\n<li>Uitstekende productieniveau<\/li>\n<\/ul>\n[\/vc_column_text][toggles style=&#8221;minimal_small&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Kenmerken&#8221;][image_with_animation image_url=&#8221;5031&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h3>RVS en gegalvaniseerd stalen zeefnetten<\/h3>\n<ul>\n<li>Voor de zwaarste toepassingen<\/li>\n<li>Mazen volgens ISO Norm 2194-1991<\/li>\n<li>Draaddiameter volgens ISO norm 4782<\/li>\n<li>Op aanvraag kunnen de hoogwaardige koolstofstalen zeefnetten gegalvaniseerd worden of corrosiebestendig zijn<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;5023&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][toggles style=&#8221;minimal_small&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Kenmerken&#8221;][image_with_animation image_url=&#8221;5033&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/toggle][\/toggles][vc_column_text]\n<h3>Zeefschermen<\/h3>\n<ul>\n<li>Geperforeerde platen<\/li>\n<li>In pianokoorden voor mobiele trilzeven, niet klevend<\/li>\n<\/ul>\n[\/vc_column_text][toggles style=&#8221;minimal_small&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Kenmerken&#8221;][image_with_animation image_url=&#8221;5035&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/toggle][\/toggles][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h3>Toebehoren en spanningssystemen<\/h3>\n<ul>\n<li>Spanplaten (1250, 1500, 1525 mm andere op aanvraag)<\/li>\n<li>Breedstraalsproeier (diameters van 4, 5, 7, 9 mm)<\/li>\n<li>Rubberen profielen in rollen van 12,5 mm<\/li>\n<li>Slotbouten en sluitringen met hamer- of ronde kop<\/li>\n<li>Transversale en longitudinale spanningssystemen<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;5041&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][toggles style=&#8221;minimal_small&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Kenmerken&#8221;][image_with_animation image_url=&#8221;5037&#8243; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_highlighted_text color_type=&#8221;gradient&#8221; highlight_color=&#8221;#f8971d&#8221; secondary_color=&#8221;rgba(0,0,0,0.01)&#8221; style=&#8221;regular_underline&#8221; underline_thickness=&#8221;default&#8221; delay=&#8221;250&#8243;]\n<h2><em>Onze meerwaarde<br \/>\n<\/em><\/h2>\n[\/nectar_highlighted_text][vc_column_text]\n<h3>Expertise &#8211; Opmetingen<\/h3>\n<ul>\n<li>Op basis van de opgegeven kenmerken selecteren wij de meest geschikte zeefnetten of -schermen voor uw toepassing.<\/li>\n<li>On site opname en opmetingen<\/li>\n<\/ul>\n<h3>Dimensionering<\/h3>\n<ul>\n<li>We kunnen,op basis van de opgegeven kenmerken, specifieke versies bestuderen aangepast aan uw trilzeven<\/li>\n<li>Expertise van de volledige aandrijving<\/li>\n<\/ul>\n<h3>Montage<\/h3>\n<ul>\n<li>Onze monteurs kunnen zeefnetten, zeefschermen en hun toebehoren plaatsen<\/li>\n<li>Snel reactievermogen 7d\/7 en 24u\/24<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;5043&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][image_with_animation image_url=&#8221;5045&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][image_with_animation image_url=&#8221;5047&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5044,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8006","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA<\/title>\n<meta name=\"description\" content=\"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA\" \/>\n<meta property=\"og:description\" content=\"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/\" \/>\n<meta property=\"og:site_name\" content=\"ABM TECNA\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-03T12:21:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/crible-mobile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ABM_TECNA\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/\",\"name\":\"Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/crible-mobile.jpg\",\"datePublished\":\"2020-07-22T09:12:00+00:00\",\"dateModified\":\"2021-05-03T12:21:19+00:00\",\"description\":\"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/crible-mobile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/crible-mobile.jpg\",\"width\":800,\"height\":450,\"caption\":\"crible mobile\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/zeefnetten-en-zeefschermen-voor-trilzeven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeefnetten en Zeefschermen voor Trilzeven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\",\"name\":\"ABM TECNA\",\"description\":\"La solution Globale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#organization\",\"name\":\"ABM TECNA\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ABMTECNA_favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ABMTECNA_favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ABM TECNA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ABM_TECNA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/abm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRJ02jgCyEoiSCooXgzd7Zg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA","description":"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/","og_locale":"nl_NL","og_type":"article","og_title":"Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA","og_description":"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar","og_url":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/","og_site_name":"ABM TECNA","article_modified_time":"2021-05-03T12:21:19+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/crible-mobile.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ABM_TECNA","twitter_misc":{"Geschatte leestijd":"10 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/","url":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/","name":"Zeefnetten en Zeefschermen voor Trilzeven - ABM TECNA","isPartOf":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/#primaryimage"},"image":{"@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/crible-mobile.jpg","datePublished":"2020-07-22T09:12:00+00:00","dateModified":"2021-05-03T12:21:19+00:00","description":"Een gamma zeefnetten en zeefschermen voor trilzeven uit hoogwaardig koolstofstaal, Anti kleef, RVS en gegalvaniseerd staal, veel toebehoren beschikbaar","breadcrumb":{"@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/#primaryimage","url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/crible-mobile.jpg","contentUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/crible-mobile.jpg","width":800,"height":450,"caption":"crible mobile"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abm-tecna.be\/nl\/zeefnetten-en-zeefschermen-voor-trilzeven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abm-tecna.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Zeefnetten en Zeefschermen voor Trilzeven"}]},{"@type":"WebSite","@id":"https:\/\/www.abm-tecna.be\/nl\/#website","url":"https:\/\/www.abm-tecna.be\/nl\/","name":"ABM TECNA","description":"La solution Globale","publisher":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abm-tecna.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.abm-tecna.be\/nl\/#organization","name":"ABM TECNA","url":"https:\/\/www.abm-tecna.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.abm-tecna.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/01\/ABMTECNA_favicon.png","contentUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/01\/ABMTECNA_favicon.png","width":512,"height":512,"caption":"ABM TECNA"},"image":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ABM_TECNA","https:\/\/www.linkedin.com\/company\/abm\/","https:\/\/www.youtube.com\/channel\/UCRJ02jgCyEoiSCooXgzd7Zg"]}]}},"_links":{"self":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/comments?post=8006"}],"version-history":[{"count":3,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8006\/revisions"}],"predecessor-version":[{"id":8558,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8006\/revisions\/8558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/media\/5044"}],"wp:attachment":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/media?parent=8006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}