{"id":8216,"date":"2019-11-26T15:44:10","date_gmt":"2019-11-26T14:44:10","guid":{"rendered":"https:\/\/abm-tecna.com\/convoyeurs-a-bandes-legeres-pvc-pu-a-bandes-modulaires-ou-tapis-metalliques\/"},"modified":"2021-05-03T13:42:27","modified_gmt":"2021-05-03T11:42:27","slug":"pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden","status":"publish","type":"page","link":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/","title":{"rendered":"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;4538&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;64&#8243; bottom_padding=&#8221;160&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; color_overlay=&#8221;#f8971d&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;256&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;triangle&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][split_line_heading animation_type=&#8221;default&#8221;]\n<h1 style=\"text-align: center;\">Andere transportbanden<\/h1>\n<p style=\"text-align: center;\">PVC\/PU lichte transportbanden, modulaire banden of metaalbanden<\/p>\n[\/split_line_heading][vc_text_separator title=&#8221;Totaaloplossing per apparatuur&#8221; border_width=&#8221;2&#8243; el_width=&#8221;60&#8243; css=&#8221;.vc_custom_1610471562605{margin-bottom: 80px !important;}&#8221;][nectar_icon_list color=&#8221;Extra-Color-3&#8243; direction=&#8221;horizontal&#8221; columns=&#8221;4&#8243; icon_size=&#8221;small&#8221; icon_style=&#8221;no-border&#8221;][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448134-3&#8243; header=&#8221;Leverancier van alle onderdelen&#8221; icon_fontawesome=&#8221;fa fa-truck&#8221; tab_id=&#8221;1616071448135-5&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448165-1&#8243; header=&#8221;Plaatsing en afstellingen&#8221; icon_fontawesome=&#8221;fa fa-cog&#8221; tab_id=&#8221;1616071448165-1&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448174-8&#8243; header=&#8221;Mechanisch onderhoud&#8221; icon_fontawesome=&#8221;fa fa-refresh&#8221; tab_id=&#8221;1616071448175-7&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448186-1&#8243; header=&#8221;Verbinding &amp; bekleding&#8221; icon_fontawesome=&#8221;fa fa-list-alt&#8221; tab_id=&#8221;1616071448187-6&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448198-9&#8243; header=&#8221;Engineering, betrouwbaarheidsverhoging&#8221; icon_fontawesome=&#8221;fa fa-calculator&#8221; tab_id=&#8221;1616071448198-9&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448211-10&#8243; header=&#8221;Vervaardiging van volledige apparatuur&#8221; icon_fontawesome=&#8221;fa fa-check-square-o&#8221; tab_id=&#8221;1616071448212-3&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448225-5&#8243; header=&#8221;Interventievermogen&#8221; icon_fontawesome=&#8221;fa fa-road&#8221; tab_id=&#8221;1616071448225-7&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; title=&#8221;List Item&#8221; id=&#8221;1616071448237-2&#8243; header=&#8221;Leverings- en\/of onderhoudscontract&#8221; icon_fontawesome=&#8221;fa fa-handshake-o&#8221; tab_id=&#8221;1616071448237-3&#8243;][vc_column_text][\/vc_column_text][\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;.links-not-on-mobile&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_html]JTIwJTVCZHJhd2F0dGVudGlvbiUyMElEJTNEJTIyODIyNiUyMiU1RA==[\/vc_raw_html][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; class=&#8221;listlinks&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-chevron-right\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li><a href=\".\/..\/nl\/moteurs-electriques\/\">Elektrische motoren<\/a><\/li>\n<li><a href=\".\/..\/nl\/variateurs-de-vitesse-basse-tension\/\">Snelheidsregelaars<\/a><\/li>\n<li><a href=\".\/..\/nl\/reducteurs-mecaniques-de-vitesse\/\">Reductiekasten<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/paliers-et-roulements\/\">Lagerhuizen en wentellagers<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/transmission-par-courroies\/\">Riemoverbrengingen<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/transmission-par-chaines\/\">Kettingoverbrenging<br \/>\n<\/a><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-chevron-right\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li><a href=\".\/..\/nl\/accouplements\/\">Koppelingen<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/bandes-modulaires-tapis-metalliques\/\">Modulaire banden en metaalbanden<\/a><\/li>\n<li><a href=\".\/..\/nl\/bandes-pvc-pu\/\">Lichte PVC en PU banden<\/a><\/li>\n<li><a href=\".\/..\/nl\/racleurs\/\">Bandschrapers<\/a><\/li>\n<li><a href=\".\/..\/nl\/rouleaux-et-supports\/\">Rollen en stellen<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/tambours\/\">Trommels<br \/>\n<\/a><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-chevron-right\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li><a href=\".\/..\/nl\/revetement-tremies-goulottes-et-cyclones\/\">Bekleding van hoppers, kokers en cyclonen<\/a><\/li>\n<li><a href=\".\/..\/nl\/revetement-tambours\/\">Bekleding van trommels<br \/>\n<\/a><\/li>\n<li><a href=\".\/..\/nl\/surveillance-et-protection-de-vos-installations\/\">Bewaking en bescherming van uw installaties<br \/>\n<\/a><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;4538&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;64&#8243; bottom_padding=&#8221;160&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; color_overlay=&#8221;#f8971d&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;256&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;triangle&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5441,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8216","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PVC\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA<\/title>\n<meta name=\"description\" content=\"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA\" \/>\n<meta property=\"og:description\" content=\"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/\" \/>\n<meta property=\"og:site_name\" content=\"ABM TECNA\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-03T11:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/CONVOYEURS-LEGERS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ABM_TECNA\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/\",\"name\":\"PVC\\\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/CONVOYEURS-LEGERS.jpg\",\"datePublished\":\"2019-11-26T14:44:10+00:00\",\"dateModified\":\"2021-05-03T11:42:27+00:00\",\"description\":\"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/CONVOYEURS-LEGERS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/CONVOYEURS-LEGERS.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Convoyeur leger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PVC\\\/PU lichte transportbanden, modulaire banden of metaalbanden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\",\"name\":\"ABM TECNA\",\"description\":\"La solution Globale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#organization\",\"name\":\"ABM TECNA\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ABMTECNA_favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.abm-tecna.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ABMTECNA_favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ABM TECNA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abm-tecna.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ABM_TECNA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/abm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRJ02jgCyEoiSCooXgzd7Zg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA","description":"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/","og_locale":"nl_NL","og_type":"article","og_title":"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA","og_description":"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.","og_url":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/","og_site_name":"ABM TECNA","article_modified_time":"2021-05-03T11:42:27+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/CONVOYEURS-LEGERS.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ABM_TECNA","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/","url":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/","name":"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden - ABM TECNA","isPartOf":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/#primaryimage"},"image":{"@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/CONVOYEURS-LEGERS.jpg","datePublished":"2019-11-26T14:44:10+00:00","dateModified":"2021-05-03T11:42:27+00:00","description":"De globale oplossing voor lichte transportbanden omvat de levering van alle reserveonderdelen voor het onderhoud of de optimalisering ervan.","breadcrumb":{"@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/#primaryimage","url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/CONVOYEURS-LEGERS.jpg","contentUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/07\/CONVOYEURS-LEGERS.jpg","width":1200,"height":1200,"caption":"Convoyeur leger"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abm-tecna.be\/nl\/pvc-pu-lichte-transportbanden-modulaire-banden-of-metaalbanden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abm-tecna.be\/nl\/"},{"@type":"ListItem","position":2,"name":"PVC\/PU lichte transportbanden, modulaire banden of metaalbanden"}]},{"@type":"WebSite","@id":"https:\/\/www.abm-tecna.be\/nl\/#website","url":"https:\/\/www.abm-tecna.be\/nl\/","name":"ABM TECNA","description":"La solution Globale","publisher":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abm-tecna.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.abm-tecna.be\/nl\/#organization","name":"ABM TECNA","url":"https:\/\/www.abm-tecna.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.abm-tecna.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/01\/ABMTECNA_favicon.png","contentUrl":"https:\/\/www.abm-tecna.be\/wp-content\/uploads\/2020\/01\/ABMTECNA_favicon.png","width":512,"height":512,"caption":"ABM TECNA"},"image":{"@id":"https:\/\/www.abm-tecna.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ABM_TECNA","https:\/\/www.linkedin.com\/company\/abm\/","https:\/\/www.youtube.com\/channel\/UCRJ02jgCyEoiSCooXgzd7Zg"]}]}},"_links":{"self":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/comments?post=8216"}],"version-history":[{"count":5,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8216\/revisions"}],"predecessor-version":[{"id":9027,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/pages\/8216\/revisions\/9027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/media\/5441"}],"wp:attachment":[{"href":"https:\/\/www.abm-tecna.be\/nl\/wp-json\/wp\/v2\/media?parent=8216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}